{"id":87201,"date":"2018-12-17T12:45:04","date_gmt":"2018-12-17T04:45:04","guid":{"rendered":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg"},"modified":"2018-12-17T12:45:04","modified_gmt":"2018-12-17T04:45:04","slug":"6069a_04-min","status":"inherit","type":"attachment","link":"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/eytys-x-hm-unisex-line\/attachment\/6069a_04-min\/","title":{"rendered":"6069A_04-min"},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6069A_04-min | Pamper.My<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6069A_04-min | Pamper.My\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Pamper.My\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pamper.My\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2337\" \/>\n\t<meta property=\"og:image:height\" content=\"3290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\",\"name\":\"Pamper.My\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Pamper.My\",\"https:\/\/instagram.com\/pamper.my\",\"http:\/\/www.youtube.com\/c\/PamperMyMalaysia\",\"https:\/\/twitter.com\/PamperMalaysia\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"contentUrl\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"width\":555,\"height\":145,\"caption\":\"Pamper.My\"},\"image\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pamper.my\/news\/#website\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"name\":\"Pamper.My\",\"description\":\"Malaysia\\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle\",\"publisher\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pamper.my\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#webpage\",\"url\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg\",\"name\":\"6069A_04-min | Pamper.My\",\"isPartOf\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#website\"},\"datePublished\":\"2018-12-17T04:45:04+00:00\",\"dateModified\":\"2018-12-17T04:45:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pamper.my\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ace The Genderless Dressing With Eytys x H&amp;M Unisex Line\",\"item\":\"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/eytys-x-hm-unisex-line\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"6069A_04-min\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6069A_04-min | Pamper.My","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg","og_locale":"en_US","og_type":"article","og_title":"6069A_04-min | Pamper.My","og_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg","og_site_name":"Pamper.My","article_publisher":"https:\/\/www.facebook.com\/Pamper.My","og_image":[{"width":2337,"height":3290,"url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.pamper.my\/news\/#organization","name":"Pamper.My","url":"https:\/\/www.pamper.my\/news\/","sameAs":["https:\/\/www.facebook.com\/Pamper.My","https:\/\/instagram.com\/pamper.my","http:\/\/www.youtube.com\/c\/PamperMyMalaysia","https:\/\/twitter.com\/PamperMalaysia"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.pamper.my\/news\/#logo","inLanguage":"en-US","url":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","contentUrl":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","width":555,"height":145,"caption":"Pamper.My"},"image":{"@id":"https:\/\/www.pamper.my\/news\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.pamper.my\/news\/#website","url":"https:\/\/www.pamper.my\/news\/","name":"Pamper.My","description":"Malaysia\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle","publisher":{"@id":"https:\/\/www.pamper.my\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamper.my\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#webpage","url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg","name":"6069A_04-min | Pamper.My","isPartOf":{"@id":"https:\/\/www.pamper.my\/news\/#website"},"datePublished":"2018-12-17T04:45:04+00:00","dateModified":"2018-12-17T04:45:04+00:00","breadcrumb":{"@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pamper.my\/news\/"},{"@type":"ListItem","position":2,"name":"Ace The Genderless Dressing With Eytys x H&amp;M Unisex Line","item":"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/eytys-x-hm-unisex-line\/"},{"@type":"ListItem","position":3,"name":"6069A_04-min"}]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a6BDs3-mGt","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-213x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-213x300.jpg 213w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-107x150.jpg 107w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-768x1081.jpg 768w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-727x1024.jpg 727w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-696x980.jpg 696w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-1068x1504.jpg 1068w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-298x420.jpg 298w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2337,"height":3290,"file":"2018\/12\/6069A_04-min.jpg","sizes":{"thumbnail":{"file":"6069A_04-min-107x150.jpg","width":107,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-107x150.jpg"},"medium":{"file":"6069A_04-min-213x300.jpg","width":213,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-213x300.jpg"},"medium_large":{"file":"6069A_04-min-768x1081.jpg","width":768,"height":1081,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-768x1081.jpg"},"large":{"file":"6069A_04-min-727x1024.jpg","width":727,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-727x1024.jpg"},"td_80x60":{"file":"6069A_04-min-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-80x60.jpg"},"td_100x70":{"file":"6069A_04-min-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-100x70.jpg"},"td_218x150":{"file":"6069A_04-min-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-218x150.jpg"},"td_265x198":{"file":"6069A_04-min-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-265x198.jpg"},"td_324x160":{"file":"6069A_04-min-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-324x160.jpg"},"td_324x235":{"file":"6069A_04-min-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-324x235.jpg"},"td_324x400":{"file":"6069A_04-min-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-324x400.jpg"},"td_356x220":{"file":"6069A_04-min-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-356x220.jpg"},"td_356x364":{"file":"6069A_04-min-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-356x364.jpg"},"td_533x261":{"file":"6069A_04-min-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-533x261.jpg"},"td_534x462":{"file":"6069A_04-min-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-534x462.jpg"},"td_696x0":{"file":"6069A_04-min-696x980.jpg","width":696,"height":980,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-696x980.jpg"},"td_696x385":{"file":"6069A_04-min-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-696x385.jpg"},"td_741x486":{"file":"6069A_04-min-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-741x486.jpg"},"td_1068x580":{"file":"6069A_04-min-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-1068x580.jpg"},"td_1068x0":{"file":"6069A_04-min-1068x1504.jpg","width":1068,"height":1504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-1068x1504.jpg"},"td_0x420":{"file":"6069A_04-min-298x420.jpg","width":298,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min-298x420.jpg"},"full":{"file":"6069A_04-min.jpg","width":2337,"height":3290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":87196,"source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2018\/12\/6069A_04-min.jpg","_links":{"self":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media\/87201"}],"collection":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/comments?post=87201"}]}}