{"id":54769,"date":"2017-09-10T23:32:36","date_gmt":"2017-09-10T15:32:36","guid":{"rendered":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg"},"modified":"2017-09-10T23:32:59","modified_gmt":"2017-09-10T15:32:59","slug":"innisfree-my-palette-case-4-modules-rm30","status":"inherit","type":"attachment","link":"https:\/\/www.pamper.my\/news\/beauty\/makeup\/customize-makeup-palette-innisfrees-style-palette\/attachment\/innisfree-my-palette-case-4-modules-rm30\/","title":{"rendered":"innisfree My Palette Case (4 modules) &#8211; RM30"},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>innisfree My Palette Case (4 modules) - RM30 | Pamper.My<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"innisfree My Palette Case (4 modules) - RM30 | Pamper.My\" \/>\n<meta property=\"og:description\" content=\"innisfree My Palette Case (4 modules) - RM30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Pamper.My\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pamper.My\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-10T15:32:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\",\"name\":\"Pamper.My\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Pamper.My\",\"https:\/\/instagram.com\/pamper.my\",\"http:\/\/www.youtube.com\/c\/PamperMyMalaysia\",\"https:\/\/twitter.com\/PamperMalaysia\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"contentUrl\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"width\":555,\"height\":145,\"caption\":\"Pamper.My\"},\"image\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pamper.my\/news\/#website\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"name\":\"Pamper.My\",\"description\":\"Malaysia\\u2019s leading beauty, fashion &amp; lifestyle media platform\",\"publisher\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pamper.my\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#webpage\",\"url\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg\",\"name\":\"innisfree My Palette Case (4 modules) - RM30 | Pamper.My\",\"isPartOf\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#website\"},\"datePublished\":\"2017-09-10T15:32:36+00:00\",\"dateModified\":\"2017-09-10T15:32:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pamper.my\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customize Your Own Makeup Palette with innisfree\\u2019s My Style, My Palette\",\"item\":\"https:\/\/www.pamper.my\/news\/beauty\/makeup\/customize-makeup-palette-innisfrees-style-palette\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"innisfree My Palette Case (4 modules) &#8211; RM30\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"innisfree My Palette Case (4 modules) - RM30 | Pamper.My","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","og_locale":"en_US","og_type":"article","og_title":"innisfree My Palette Case (4 modules) - RM30 | Pamper.My","og_description":"innisfree My Palette Case (4 modules) - RM30","og_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","og_site_name":"Pamper.My","article_publisher":"https:\/\/www.facebook.com\/Pamper.My","article_modified_time":"2017-09-10T15:32:59+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.pamper.my\/news\/#organization","name":"Pamper.My","url":"https:\/\/www.pamper.my\/news\/","sameAs":["https:\/\/www.facebook.com\/Pamper.My","https:\/\/instagram.com\/pamper.my","http:\/\/www.youtube.com\/c\/PamperMyMalaysia","https:\/\/twitter.com\/PamperMalaysia"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.pamper.my\/news\/#logo","inLanguage":"en-US","url":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","contentUrl":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","width":555,"height":145,"caption":"Pamper.My"},"image":{"@id":"https:\/\/www.pamper.my\/news\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.pamper.my\/news\/#website","url":"https:\/\/www.pamper.my\/news\/","name":"Pamper.My","description":"Malaysia\u2019s leading beauty, fashion &amp; lifestyle media platform","publisher":{"@id":"https:\/\/www.pamper.my\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamper.my\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#webpage","url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","name":"innisfree My Palette Case (4 modules) - RM30 | Pamper.My","isPartOf":{"@id":"https:\/\/www.pamper.my\/news\/#website"},"datePublished":"2017-09-10T15:32:36+00:00","dateModified":"2017-09-10T15:32:59+00:00","breadcrumb":{"@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pamper.my\/news\/"},{"@type":"ListItem","position":2,"name":"Customize Your Own Makeup Palette with innisfree\u2019s My Style, My Palette","item":"https:\/\/www.pamper.my\/news\/beauty\/makeup\/customize-makeup-palette-innisfrees-style-palette\/"},{"@type":"ListItem","position":3,"name":"innisfree My Palette Case (4 modules) &#8211; RM30"}]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a6BDs3-efn","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-300x300.jpeg 300w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-150x150.jpeg 150w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-420x420.jpeg 420w, https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>innisfree My Palette Case (4 modules) &#8211; RM30<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":450,"file":"2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","sizes":{"thumbnail":{"file":"innisfree-My-Palette-Case-4-modules-RM30-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-150x150.jpeg"},"medium":{"file":"innisfree-My-Palette-Case-4-modules-RM30-300x300.jpeg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-300x300.jpeg"},"td_80x60":{"file":"innisfree-My-Palette-Case-4-modules-RM30-80x60.jpeg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-80x60.jpeg"},"td_100x70":{"file":"innisfree-My-Palette-Case-4-modules-RM30-100x70.jpeg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-100x70.jpeg"},"td_218x150":{"file":"innisfree-My-Palette-Case-4-modules-RM30-218x150.jpeg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-218x150.jpeg"},"td_265x198":{"file":"innisfree-My-Palette-Case-4-modules-RM30-265x198.jpeg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-265x198.jpeg"},"td_324x160":{"file":"innisfree-My-Palette-Case-4-modules-RM30-324x160.jpeg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-324x160.jpeg"},"td_324x235":{"file":"innisfree-My-Palette-Case-4-modules-RM30-324x235.jpeg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-324x235.jpeg"},"td_324x400":{"file":"innisfree-My-Palette-Case-4-modules-RM30-324x400.jpeg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-324x400.jpeg"},"td_356x220":{"file":"innisfree-My-Palette-Case-4-modules-RM30-356x220.jpeg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-356x220.jpeg"},"td_356x364":{"file":"innisfree-My-Palette-Case-4-modules-RM30-356x364.jpeg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-356x364.jpeg"},"td_533x261":{"file":"innisfree-My-Palette-Case-4-modules-RM30-450x261.jpeg","width":450,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-450x261.jpeg"},"td_696x385":{"file":"innisfree-My-Palette-Case-4-modules-RM30-450x385.jpeg","width":450,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-450x385.jpeg"},"td_0x420":{"file":"innisfree-My-Palette-Case-4-modules-RM30-420x420.jpeg","width":420,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30-420x420.jpeg"},"full":{"file":"innisfree-My-Palette-Case-4-modules-RM30.jpeg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg"}},"image_meta":{"aperture":"0","credit":"osx","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":54761,"source_url":"https:\/\/www.pamper.my\/news\/wp-content\/uploads\/2017\/09\/innisfree-My-Palette-Case-4-modules-RM30.jpeg","_links":{"self":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media\/54769"}],"collection":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/comments?post=54769"}]}}