{"id":104166,"date":"2021-02-24T18:03:31","date_gmt":"2021-02-24T10:03:31","guid":{"rendered":"http:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg"},"modified":"2021-02-24T18:04:28","modified_gmt":"2021-02-24T10:04:28","slug":"dr-dennis-gross-b3-adaptive-superfoods-rescue-super-serum","status":"inherit","type":"attachment","link":"https:\/\/www.pamper.my\/news\/beauty\/sephoras-spring-2021-launches-set-to-unleash-the-beauty-power-in-you\/attachment\/dr-dennis-gross-b3-adaptive-superfoods-rescue-super-serum\/","title":{"rendered":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum"},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My\" \/>\n<meta property=\"og:description\" content=\"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum is scientifically engineered microcapsules of superfoods, adaptogens, and niacinamide (B3) in a powerful anti-stress serum for boosted absorption of vital nutrients that help correct and prevent visible signs of stress.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Pamper.My\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pamper.My\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T10:04:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\",\"name\":\"Pamper.My\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Pamper.My\",\"https:\/\/instagram.com\/pamper.my\",\"http:\/\/www.youtube.com\/c\/PamperMyMalaysia\",\"https:\/\/twitter.com\/PamperMalaysia\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"contentUrl\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"width\":555,\"height\":145,\"caption\":\"Pamper.My\"},\"image\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pamper.my\/news\/#website\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"name\":\"Pamper.My\",\"description\":\"Malaysia\\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle\",\"publisher\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pamper.my\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#webpage\",\"url\":\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg\",\"name\":\"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My\",\"isPartOf\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#website\"},\"datePublished\":\"2021-02-24T10:03:31+00:00\",\"dateModified\":\"2021-02-24T10:04:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pamper.my\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sephora&#8217;s Spring 2021 Launches Set to Unleash the Beauty Power in YOU\",\"item\":\"https:\/\/www.pamper.my\/news\/beauty\/sephoras-spring-2021-launches-set-to-unleash-the-beauty-power-in-you\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","og_locale":"en_US","og_type":"article","og_title":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My","og_description":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum is scientifically engineered microcapsules of superfoods, adaptogens, and niacinamide (B3) in a powerful anti-stress serum for boosted absorption of vital nutrients that help correct and prevent visible signs of stress.","og_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","og_site_name":"Pamper.My","article_publisher":"https:\/\/www.facebook.com\/Pamper.My","article_modified_time":"2021-02-24T10:04:28+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.pamper.my\/news\/#organization","name":"Pamper.My","url":"https:\/\/www.pamper.my\/news\/","sameAs":["https:\/\/www.facebook.com\/Pamper.My","https:\/\/instagram.com\/pamper.my","http:\/\/www.youtube.com\/c\/PamperMyMalaysia","https:\/\/twitter.com\/PamperMalaysia"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.pamper.my\/news\/#logo","inLanguage":"en-US","url":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","contentUrl":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","width":555,"height":145,"caption":"Pamper.My"},"image":{"@id":"https:\/\/www.pamper.my\/news\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.pamper.my\/news\/#website","url":"https:\/\/www.pamper.my\/news\/","name":"Pamper.My","description":"Malaysia\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle","publisher":{"@id":"https:\/\/www.pamper.my\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamper.my\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#webpage","url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","name":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum | Pamper.My","isPartOf":{"@id":"https:\/\/www.pamper.my\/news\/#website"},"datePublished":"2021-02-24T10:03:31+00:00","dateModified":"2021-02-24T10:04:28+00:00","breadcrumb":{"@id":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pamper.my\/news\/"},{"@type":"ListItem","position":2,"name":"Sephora&#8217;s Spring 2021 Launches Set to Unleash the Beauty Power in YOU","item":"https:\/\/www.pamper.my\/news\/beauty\/sephoras-spring-2021-launches-set-to-unleash-the-beauty-power-in-you\/"},{"@type":"ListItem","position":3,"name":"Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum"}]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a6BDs3-r66","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-300x300.jpg 300w, https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-150x150.jpg 150w, https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-768x768.jpg 768w, https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-696x696.jpg 696w, https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-420x420.jpg 420w, https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Dr. Dennis Gross B3 Adaptive SuperFoods Rescue Super Serum is scientifically engineered microcapsules of superfoods, adaptogens, and niacinamide (B3) in a powerful anti-stress serum for boosted absorption of vital nutrients that help correct and prevent visible signs of stress.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":1024,"file":"2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","sizes":{"thumbnail":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-150x150.jpg"},"medium":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-300x300.jpg"},"medium_large":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-768x768.jpg"},"td_80x60":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-80x60.jpg"},"td_100x70":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-100x70.jpg"},"td_218x150":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-218x150.jpg"},"td_265x198":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-265x198.jpg"},"td_324x160":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x160.jpg"},"td_324x235":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x235.jpg"},"td_324x400":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-324x400.jpg"},"td_356x220":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-356x220.jpg"},"td_356x364":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-356x364.jpg"},"td_533x261":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-533x261.jpg"},"td_534x462":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-534x462.jpg"},"td_696x0":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-696x696.jpg","width":696,"height":696,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-696x696.jpg"},"td_696x385":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-696x385.jpg"},"td_741x486":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-741x486.jpg"},"td_1068x580":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-1024x580.jpg","width":1024,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-1024x580.jpg"},"td_0x420":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-420x420.jpg","width":420,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum-420x420.jpg"},"full":{"file":"Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"filesize":38969},"post":104162,"source_url":"https:\/\/media.pamper.my\/2021\/02\/Dr.-Dennis-Gross-B3-Adaptive-SuperFoods-Rescue-Super-Serum.jpg","_links":{"self":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media\/104166"}],"collection":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/comments?post=104166"}]}}