{"id":102215,"date":"2020-11-10T12:13:52","date_gmt":"2020-11-10T04:13:52","guid":{"rendered":"http:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg"},"modified":"2020-11-10T12:13:52","modified_gmt":"2020-11-10T04:13:52","slug":"pomelo-11-11-schedule-1","status":"inherit","type":"attachment","link":"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/pomelo-11-11-mega-fashion-sale-offers-massive-savings-up-to-90-off\/attachment\/pomelo-11-11-schedule-1\/","title":{"rendered":"Pomelo 11.11 &#8211; Schedule (1)"},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pomelo 11.11 - Schedule (1) | Pamper.My<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pomelo 11.11 - Schedule (1) | Pamper.My\" \/>\n<meta property=\"og:url\" content=\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Pamper.My\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pamper.My\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-768x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\",\"name\":\"Pamper.My\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Pamper.My\",\"https:\/\/instagram.com\/pamper.my\",\"http:\/\/www.youtube.com\/c\/PamperMyMalaysia\",\"https:\/\/twitter.com\/PamperMalaysia\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"contentUrl\":\"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png\",\"width\":555,\"height\":145,\"caption\":\"Pamper.My\"},\"image\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pamper.my\/news\/#website\",\"url\":\"https:\/\/www.pamper.my\/news\/\",\"name\":\"Pamper.My\",\"description\":\"Malaysia\\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle\",\"publisher\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pamper.my\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#webpage\",\"url\":\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg\",\"name\":\"Pomelo 11.11 - Schedule (1) | Pamper.My\",\"isPartOf\":{\"@id\":\"https:\/\/www.pamper.my\/news\/#website\"},\"datePublished\":\"2020-11-10T04:13:52+00:00\",\"dateModified\":\"2020-11-10T04:13:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pamper.my\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pomelo 11.11 Mega Fashion Sale Offers Massive Savings up to 90% OFF\",\"item\":\"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/pomelo-11-11-mega-fashion-sale-offers-massive-savings-up-to-90-off\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pomelo 11.11 &#8211; Schedule (1)\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pomelo 11.11 - Schedule (1) | Pamper.My","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg","og_locale":"en_US","og_type":"article","og_title":"Pomelo 11.11 - Schedule (1) | Pamper.My","og_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg","og_site_name":"Pamper.My","article_publisher":"https:\/\/www.facebook.com\/Pamper.My","og_image":[{"width":768,"height":1024,"url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-768x1024.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.pamper.my\/news\/#organization","name":"Pamper.My","url":"https:\/\/www.pamper.my\/news\/","sameAs":["https:\/\/www.facebook.com\/Pamper.My","https:\/\/instagram.com\/pamper.my","http:\/\/www.youtube.com\/c\/PamperMyMalaysia","https:\/\/twitter.com\/PamperMalaysia"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.pamper.my\/news\/#logo","inLanguage":"en-US","url":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","contentUrl":"http:\/\/media.pamper.my\/2022\/06\/Pamper.My-Logo-new.png","width":555,"height":145,"caption":"Pamper.My"},"image":{"@id":"https:\/\/www.pamper.my\/news\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.pamper.my\/news\/#website","url":"https:\/\/www.pamper.my\/news\/","name":"Pamper.My","description":"Malaysia\u2019s leading digital magazine for beauty, fashion, wellness &amp; lifestyle","publisher":{"@id":"https:\/\/www.pamper.my\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pamper.my\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#webpage","url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg","name":"Pomelo 11.11 - Schedule (1) | Pamper.My","isPartOf":{"@id":"https:\/\/www.pamper.my\/news\/#website"},"datePublished":"2020-11-10T04:13:52+00:00","dateModified":"2020-11-10T04:13:52+00:00","breadcrumb":{"@id":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pamper.my\/news\/"},{"@type":"ListItem","position":2,"name":"Pomelo 11.11 Mega Fashion Sale Offers Massive Savings up to 90% OFF","item":"https:\/\/www.pamper.my\/news\/lifestyle\/fashion\/pomelo-11-11-mega-fashion-sale-offers-massive-savings-up-to-90-off\/"},{"@type":"ListItem","position":3,"name":"Pomelo 11.11 &#8211; Schedule (1)"}]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a6BDs3-qAD","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-225x300.jpg 225w, https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-113x150.jpg 113w, https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-768x1024.jpg 768w, https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-696x928.jpg 696w, https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-1068x1424.jpg 1068w, https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-315x420.jpg 315w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":5001,"height":6667,"file":"2020\/11\/Pomelo-11.11-Schedule-1.jpg","sizes":{"thumbnail":{"file":"Pomelo-11.11-Schedule-1-113x150.jpg","width":113,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-113x150.jpg"},"medium":{"file":"Pomelo-11.11-Schedule-1-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-225x300.jpg"},"medium_large":{"file":"Pomelo-11.11-Schedule-1-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-768x1024.jpg"},"large":{"file":"Pomelo-11.11-Schedule-1-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-768x1024.jpg"},"td_80x60":{"file":"Pomelo-11.11-Schedule-1-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-80x60.jpg"},"td_100x70":{"file":"Pomelo-11.11-Schedule-1-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-100x70.jpg"},"td_218x150":{"file":"Pomelo-11.11-Schedule-1-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-218x150.jpg"},"td_265x198":{"file":"Pomelo-11.11-Schedule-1-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-265x198.jpg"},"td_324x160":{"file":"Pomelo-11.11-Schedule-1-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-324x160.jpg"},"td_324x235":{"file":"Pomelo-11.11-Schedule-1-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-324x235.jpg"},"td_324x400":{"file":"Pomelo-11.11-Schedule-1-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-324x400.jpg"},"td_356x220":{"file":"Pomelo-11.11-Schedule-1-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-356x220.jpg"},"td_356x364":{"file":"Pomelo-11.11-Schedule-1-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-356x364.jpg"},"td_533x261":{"file":"Pomelo-11.11-Schedule-1-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-533x261.jpg"},"td_534x462":{"file":"Pomelo-11.11-Schedule-1-534x462.jpg","width":534,"height":462,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-534x462.jpg"},"td_696x0":{"file":"Pomelo-11.11-Schedule-1-696x928.jpg","width":696,"height":928,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-696x928.jpg"},"td_696x385":{"file":"Pomelo-11.11-Schedule-1-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-696x385.jpg"},"td_741x486":{"file":"Pomelo-11.11-Schedule-1-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-741x486.jpg"},"td_1068x580":{"file":"Pomelo-11.11-Schedule-1-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-1068x580.jpg"},"td_1068x0":{"file":"Pomelo-11.11-Schedule-1-1068x1424.jpg","width":1068,"height":1424,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-1068x1424.jpg"},"td_0x420":{"file":"Pomelo-11.11-Schedule-1-315x420.jpg","width":315,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1-315x420.jpg"},"full":{"file":"Pomelo-11.11-Schedule-1.jpg","width":5001,"height":6667,"mime_type":"image\/jpeg","source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":3501930},"post":102209,"source_url":"https:\/\/media.pamper.my\/2020\/11\/Pomelo-11.11-Schedule-1.jpg","_links":{"self":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media\/102215"}],"collection":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pamper.my\/news\/wp-json\/wp\/v2\/comments?post=102215"}]}}